{"id":1,"date":"2016-11-08T20:30:47","date_gmt":"2016-11-08T19:30:47","guid":{"rendered":"http:\/\/www.weihnachtsbaum-schwarz.de\/cms\/?p=1"},"modified":"2016-11-08T20:30:47","modified_gmt":"2016-11-08T19:30:47","slug":"hallo-welt","status":"publish","type":"post","link":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/2016\/11\/08\/hallo-welt\/","title":{"rendered":"Hallo Welt!"},"content":{"rendered":"<p>Willkommen zur deutschen Version von WordPress. Dies ist der erste Beitrag. Du kannst ihn bearbeiten oder l\u00f6schen. Und dann starte mit dem Schreiben!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen zur deutschen Version von WordPress. Dies ist der erste Beitrag. Du kannst ihn bearbeiten oder l\u00f6schen. Und dann starte mit dem Schreiben!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[1],"tags":[],"brand":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/tags?post=1"},{"taxonomy":"brand","embeddable":true,"href":"http:\/\/www.weihnachtsbaum-schwarz.de\/index.php\/wp-json\/wp\/v2\/brand?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}